{"id":804,"count":1,"description":"","link":"https:\/\/www.holidaylandmark.com\/blog\/category\/bikaner\/","name":"Bikaner","slug":"bikaner","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.holidaylandmark.com\/blog\/wp-json\/wp\/v2\/categories\/804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.holidaylandmark.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.holidaylandmark.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.holidaylandmark.com\/blog\/wp-json\/wp\/v2\/posts?categories=804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}